{"id":367,"date":"2024-12-04T20:28:46","date_gmt":"2024-12-04T20:28:46","guid":{"rendered":"https:\/\/rousseauimmo.com\/?page_id=367"},"modified":"2024-12-04T20:28:46","modified_gmt":"2024-12-04T20:28:46","slug":"two-or-more-storey","status":"publish","type":"page","link":"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/","title":{"rendered":"Two or more storey"},"content":{"rendered":"<!-- Starting MW Properties \/ Shortcode ID: e4f6b2356cce --><div id=\"mix-container-e4f6b2356cce\" class=\"mix-container\"><div class=\"col-xl-3 col-lg-4 col-md-6 col-12 p-1\">\n\t\t\t\t<a href=\"https:\/\/rousseauimmo.com\/en\/properties\/621+Rue+du+Sauternes\/14924486\" class=\"d-block position-relative\">\n\t\t\t\t\n\t\t\t\t<div class=\"property-box\">\n                \t\t\t\t\t<div class=\"img\">\n                \t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/14924486\/thumbs-320\/14924486-01.jpg\" data-src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/14924486\/14924486-01.jpg\" class=\"lazyload\" alt=\"621 Rue du Sauternes\" >\n                \t\t\t\t\t<\/div>\n                \t\t\t\t\t<div class=\"text\">\n                \t\t\t\t\t\t<div class=\"box_infos_maison\">\n                \t\t\t\t\t\t\t<div class=\"secteur_maison\">\n                \t\t\t\t\t\t\t\tRosem\u00e8re\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"prix_maison\">\n                                               $1,099,000\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"bath\">\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-home.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bed.png\" alt=\"\" \/> 4<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bath.png\" alt=\"\" \/> 2<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-handwsh.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t<div class=\"bottom\">\n                \t\t\t\t\t\t\t\t<div class=\"address\">\n                \t\t\t\t\t\t\t\t\t621 Rue du Sauternes\n                \t\t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t\t<p>Two or more storey<\/p> <small>Centris # 14924486<\/small>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t<\/div>\n                \t\t\t\t\t<\/div>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<property-meta type='mls' style='display: none;'>14924486<\/property-meta><\/div><div class=\"col-xl-3 col-lg-4 col-md-6 col-12 p-1\">\n\t\t\t\t<a href=\"https:\/\/rousseauimmo.com\/en\/properties\/8250+Rue+du+Jabot\/25303099\" class=\"d-block position-relative\">\n\t\t\t\t\n\t\t\t\t<div class=\"property-box\">\n                \t\t\t\t\t<div class=\"img\">\n                \t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/25303099\/thumbs-320\/25303099-01.jpg\" data-src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/25303099\/25303099-01.jpg\" class=\"lazyload\" alt=\"8250 Rue du Jabot\" >\n                \t\t\t\t\t<\/div>\n                \t\t\t\t\t<div class=\"text\">\n                \t\t\t\t\t\t<div class=\"box_infos_maison\">\n                \t\t\t\t\t\t\t<div class=\"secteur_maison\">\n                \t\t\t\t\t\t\t\tTerrebonne (La Plaine)\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"prix_maison\">\n                                               $779,990\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"bath\">\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-home.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bed.png\" alt=\"\" \/> 4<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bath.png\" alt=\"\" \/> 2<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-handwsh.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t<div class=\"bottom\">\n                \t\t\t\t\t\t\t\t<div class=\"address\">\n                \t\t\t\t\t\t\t\t\t8250 Rue du Jabot\n                \t\t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t\t<p>Two or more storey<\/p> <small>Centris # 25303099<\/small>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t<\/div>\n                \t\t\t\t\t<\/div>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<property-meta type='mls' style='display: none;'>25303099<\/property-meta><\/div><div class=\"col-xl-3 col-lg-4 col-md-6 col-12 p-1\">\n\t\t\t\t<a href=\"https:\/\/rousseauimmo.com\/en\/properties\/261+9e+Rang\/26594240\" class=\"d-block position-relative\">\n\t\t\t\t<div class=\"prop-label new\">New<\/div>\n\t\t\t\t<div class=\"property-box\">\n                \t\t\t\t\t<div class=\"img\">\n                \t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/26594240\/thumbs-320\/26594240-01.jpg\" data-src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/26594240\/26594240-01.jpg\" class=\"lazyload\" alt=\"261 9e Rang\" >\n                \t\t\t\t\t<\/div>\n                \t\t\t\t\t<div class=\"text\">\n                \t\t\t\t\t\t<div class=\"box_infos_maison\">\n                \t\t\t\t\t\t\t<div class=\"secteur_maison\">\n                \t\t\t\t\t\t\t\tSaint-C\u00f4me\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"prix_maison\">\n                                               $744,900\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"bath\">\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-home.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bed.png\" alt=\"\" \/> 4<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bath.png\" alt=\"\" \/> 2<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-handwsh.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t<div class=\"bottom\">\n                \t\t\t\t\t\t\t\t<div class=\"address\">\n                \t\t\t\t\t\t\t\t\t261 9e Rang\n                \t\t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t\t<p>Two or more storey<\/p> <small>Centris # 26594240<\/small>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t<\/div>\n                \t\t\t\t\t<\/div>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<property-meta type='mls' style='display: none;'>26594240<\/property-meta><\/div><div class=\"col-xl-3 col-lg-4 col-md-6 col-12 p-1\">\n\t\t\t\t<a href=\"https:\/\/rousseauimmo.com\/en\/properties\/2755+Rue+des+Sables\/10732106\" class=\"d-block position-relative\">\n\t\t\t\t\n\t\t\t\t<div class=\"property-box\">\n                \t\t\t\t\t<div class=\"img\">\n                \t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/10732106\/thumbs-320\/10732106-01.jpg\" data-src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/10732106\/10732106-01.jpg\" class=\"lazyload\" alt=\"2755 Rue des Sables\" >\n                \t\t\t\t\t<\/div>\n                \t\t\t\t\t<div class=\"text\">\n                \t\t\t\t\t\t<div class=\"box_infos_maison\">\n                \t\t\t\t\t\t\t<div class=\"secteur_maison\">\n                \t\t\t\t\t\t\t\tSainte-Julienne\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"prix_maison\">\n                                               $699,000\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"bath\">\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-home.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bed.png\" alt=\"\" \/> 5<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bath.png\" alt=\"\" \/> 1<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-handwsh.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t<div class=\"bottom\">\n                \t\t\t\t\t\t\t\t<div class=\"address\">\n                \t\t\t\t\t\t\t\t\t2755 Rue des Sables\n                \t\t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t\t<p>Two or more storey<\/p> <small>Centris # 10732106<\/small>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t<\/div>\n                \t\t\t\t\t<\/div>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<property-meta type='mls' style='display: none;'>10732106<\/property-meta><\/div><div class=\"col-xl-3 col-lg-4 col-md-6 col-12 p-1\">\n\t\t\t\t<a href=\"https:\/\/rousseauimmo.com\/en\/properties\/423+3e+Avenue+E.\/21576815\" class=\"d-block position-relative\">\n\t\t\t\t\n\t\t\t\t<div class=\"property-box\">\n                \t\t\t\t\t<div class=\"img\">\n                \t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/21576815\/thumbs-320\/21576815-01.jpg\" data-src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/21576815\/21576815-01.jpg\" class=\"lazyload\" alt=\"423 3e Avenue E.\" >\n                \t\t\t\t\t<\/div>\n                \t\t\t\t\t<div class=\"text\">\n                \t\t\t\t\t\t<div class=\"box_infos_maison\">\n                \t\t\t\t\t\t\t<div class=\"secteur_maison\">\n                \t\t\t\t\t\t\t\tCrabtree\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"prix_maison\">\n                                               $599,900\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"bath\">\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-home.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bed.png\" alt=\"\" \/> 6<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bath.png\" alt=\"\" \/> 1<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-handwsh.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t<div class=\"bottom\">\n                \t\t\t\t\t\t\t\t<div class=\"address\">\n                \t\t\t\t\t\t\t\t\t423 3e Avenue E.\n                \t\t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t\t<p>Two or more storey<\/p> <small>Centris # 21576815<\/small>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t<\/div>\n                \t\t\t\t\t<\/div>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<property-meta type='mls' style='display: none;'>21576815<\/property-meta><\/div><div class=\"col-xl-3 col-lg-4 col-md-6 col-12 p-1\">\n\t\t\t\t<a href=\"https:\/\/rousseauimmo.com\/en\/properties\/13545+Rue+du+Charretier\/23573662\" class=\"d-block position-relative\">\n\t\t\t\t<div class=\"prop-label new\">New<\/div>\n\t\t\t\t<div class=\"property-box\">\n                \t\t\t\t\t<div class=\"img\">\n                \t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/23573662\/thumbs-320\/23573662-01.jpg\" data-src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/23573662\/23573662-01.jpg\" class=\"lazyload\" alt=\"13545 Rue du Charretier\" >\n                \t\t\t\t\t<\/div>\n                \t\t\t\t\t<div class=\"text\">\n                \t\t\t\t\t\t<div class=\"box_infos_maison\">\n                \t\t\t\t\t\t\t<div class=\"secteur_maison\">\n                \t\t\t\t\t\t\t\tMirabel\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"prix_maison\">\n                                               $549,990\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"bath\">\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-home.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bed.png\" alt=\"\" \/> 3<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bath.png\" alt=\"\" \/> 1<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-handwsh.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t<div class=\"bottom\">\n                \t\t\t\t\t\t\t\t<div class=\"address\">\n                \t\t\t\t\t\t\t\t\t13545 Rue du Charretier\n                \t\t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t\t<p>Two or more storey<\/p> <small>Centris # 23573662<\/small>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t<\/div>\n                \t\t\t\t\t<\/div>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<property-meta type='mls' style='display: none;'>23573662<\/property-meta><\/div><div class=\"col-xl-3 col-lg-4 col-md-6 col-12 p-1\">\n\t\t\t\t<a href=\"https:\/\/rousseauimmo.com\/en\/properties\/38+Ch.+Piperno\/11137402\" class=\"d-block position-relative\">\n\t\t\t\t\n\t\t\t\t<div class=\"property-box\">\n                \t\t\t\t\t<div class=\"img\">\n                \t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/11137402\/thumbs-320\/11137402-01.jpg\" data-src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/11137402\/11137402-01.jpg\" class=\"lazyload\" alt=\"38 Ch. Piperno\" >\n                \t\t\t\t\t<\/div>\n                \t\t\t\t\t<div class=\"text\">\n                \t\t\t\t\t\t<div class=\"box_infos_maison\">\n                \t\t\t\t\t\t\t<div class=\"secteur_maison\">\n                \t\t\t\t\t\t\t\tSaint-Donat\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"prix_maison\">\n                                               $549,800\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"bath\">\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-home.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bed.png\" alt=\"\" \/> 3<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bath.png\" alt=\"\" \/> 2<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-handwsh.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t<div class=\"bottom\">\n                \t\t\t\t\t\t\t\t<div class=\"address\">\n                \t\t\t\t\t\t\t\t\t38 Ch. Piperno\n                \t\t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t\t<p>Two or more storey<\/p> <small>Centris # 11137402<\/small>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t<\/div>\n                \t\t\t\t\t<\/div>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<property-meta type='mls' style='display: none;'>11137402<\/property-meta><\/div><div class=\"col-xl-3 col-lg-4 col-md-6 col-12 p-1\">\n\t\t\t\t<a href=\"https:\/\/rousseauimmo.com\/en\/properties\/252+Rue+St-Joseph\/16974523\" class=\"d-block position-relative\">\n\t\t\t\t<div class=\"prop-label new\">New<\/div>\n\t\t\t\t<div class=\"property-box\">\n                \t\t\t\t\t<div class=\"img\">\n                \t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/16974523\/thumbs-320\/16974523-01.jpg\" data-src=\"https:\/\/realestate.marketingwebsites.ca\/property-images\/16974523\/16974523-01.jpg\" class=\"lazyload\" alt=\"252 Rue St-Joseph\" >\n                \t\t\t\t\t<\/div>\n                \t\t\t\t\t<div class=\"text\">\n                \t\t\t\t\t\t<div class=\"box_infos_maison\">\n                \t\t\t\t\t\t\t<div class=\"secteur_maison\">\n                \t\t\t\t\t\t\t\tTerrebonne (Terrebonne)\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"prix_maison\">\n                                               $399,999\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t                \t\t\t\t\t\t\t<div class=\"bath\">\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-home.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bed.png\" alt=\"\" \/> 3<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-bath.png\" alt=\"\" \/> 1<\/div>\n                \t\t\t\t\t\t\t\t<div class=\"d-none\"><img decoding=\"async\" src=\"https:\/\/rousseauimmo.com\/wp-content\/themes\/benjamin-rousseau\/assets\/img\/icon-handwsh.png\" alt=\"\" \/><\/div>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t<div class=\"bottom\">\n                \t\t\t\t\t\t\t\t<div class=\"address\">\n                \t\t\t\t\t\t\t\t\t252 Rue St-Joseph\n                \t\t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t\t\t<p>Two or more storey<\/p> <small>Centris # 16974523<\/small>\n                \t\t\t\t\t\t\t<\/div>\n                \t\t\t\t\t\t<\/div>\n                \t\t\t\t\t<\/div>\n                \t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t<property-meta type='mls' style='display: none;'>16974523<\/property-meta><\/div><\/div><div class=\"col-sm-12\"><div id=\"pagination-wrapper\" class=\"mixitup-page-list text-center\"><\/div><\/div><!-- Ending MW Properties \/ Shortcode ID: e4f6b2356cce -->\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-367","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Two or more storey - Benjamin Rousseau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Two or more storey - Benjamin Rousseau\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/\" \/>\n<meta property=\"og:site_name\" content=\"Benjamin Rousseau\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rousseauimmo.com\/wp-content\/uploads\/2024\/12\/og.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1889\" \/>\n\t<meta property=\"og:image:height\" content=\"941\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/\",\"url\":\"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/\",\"name\":\"Two or more storey - Benjamin Rousseau\",\"isPartOf\":{\"@id\":\"https:\/\/rousseauimmo.com\/en\/#website\"},\"datePublished\":\"2024-12-04T20:28:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/rousseauimmo.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Two or more storey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rousseauimmo.com\/en\/#website\",\"url\":\"https:\/\/rousseauimmo.com\/en\/\",\"name\":\"Benjamin Rousseau\",\"description\":\"Courtier immobilier - eXp\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rousseauimmo.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Two or more storey - Benjamin Rousseau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/","og_locale":"en_US","og_type":"article","og_title":"Two or more storey - Benjamin Rousseau","og_url":"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/","og_site_name":"Benjamin Rousseau","og_image":[{"width":1889,"height":941,"url":"https:\/\/rousseauimmo.com\/wp-content\/uploads\/2024\/12\/og.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/","url":"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/","name":"Two or more storey - Benjamin Rousseau","isPartOf":{"@id":"https:\/\/rousseauimmo.com\/en\/#website"},"datePublished":"2024-12-04T20:28:46+00:00","breadcrumb":{"@id":"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/rousseauimmo.com\/en\/two-or-more-storey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/rousseauimmo.com\/en\/"},{"@type":"ListItem","position":2,"name":"Two or more storey"}]},{"@type":"WebSite","@id":"https:\/\/rousseauimmo.com\/en\/#website","url":"https:\/\/rousseauimmo.com\/en\/","name":"Benjamin Rousseau","description":"Courtier immobilier - eXp","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rousseauimmo.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/rousseauimmo.com\/en\/wp-json\/wp\/v2\/pages\/367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rousseauimmo.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rousseauimmo.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rousseauimmo.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/rousseauimmo.com\/en\/wp-json\/wp\/v2\/comments?post=367"}],"version-history":[{"count":1,"href":"https:\/\/rousseauimmo.com\/en\/wp-json\/wp\/v2\/pages\/367\/revisions"}],"predecessor-version":[{"id":368,"href":"https:\/\/rousseauimmo.com\/en\/wp-json\/wp\/v2\/pages\/367\/revisions\/368"}],"wp:attachment":[{"href":"https:\/\/rousseauimmo.com\/en\/wp-json\/wp\/v2\/media?parent=367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}